{"id":1773,"date":"2015-05-07T14:17:33","date_gmt":"2015-05-07T14:17:33","guid":{"rendered":"https:\/\/dorimedia.com\/?p=1773"},"modified":"2016-12-12T13:58:41","modified_gmt":"2016-12-12T13:58:41","slug":"la-screenings-2","status":"publish","type":"post","link":"https:\/\/dorimedia.com\/es\/publications\/la-screenings-2\/","title":{"rendered":"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \u00abESPERANZA MIA\u00bb Y \u00abJUEGO DE CHEFS\u00bb"},"content":{"rendered":"<p><strong><em>\u201cEsperanza Mia\u201d es el segundo programa m\u00e1s visto en Argentina y ha tenido el mejor rendimiento en su horario de 9:00 pm desde su debut.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0\u201cJuego de Chefs\u201d est\u00e1 por lanzarse en Alemanis continuando el gran rating en Israel<\/em><\/strong><\/p>\n<p>Dori Media Group (\u201cDMG\u201d, \u201cla Compa\u00f1\u00eda\u201d) anuncia que asistir\u00e1 a LA Screenings 2015 con una gran selecci\u00f3n de programas, incluyendo los nuevos t\u00edtulos \u201cEsperanza M\u00eda\u201d (My Lovely Hope) y \u201cJuego de Chefs\u201d, ambos est\u00e1n consiguiendo r\u00e1pido reconocimiento en sus respectivos mercados.<\/p>\n<p>\u201cEsperanza M\u00eda\u201d, la comedia rom\u00e1ntica que DMG co produce con Pol-ka Producciones, est\u00e1 ganando su franja en el horario del prime time de las 9:00 PM. Logr\u00f3 una calificaci\u00f3n promedio de 16.4 y un share de audiencia del 20 % durante la primera semana, convirti\u00e9ndose en el segundo programa m\u00e1s visto de Argentina desde que sali\u00f3 al aire hace casi un mes, poni\u00e9ndose por delante de la segunda temporada de \u201cMaster Chef\u201d y \u201cElegidos\u201d. La comedia rom\u00e1ntica ha sido vendida a Indonesia, Vietnam e Israel.<\/p>\n<p>\u201cJuego de Chefs\u201d, un programa gastron\u00f3mico producido por Lab y ITV Studios para el canal Reshet, ha conseguido un incremento del share de audiencia del 39.9% en Israel y ha sido vendido a Vox en Alemania, donde se ha duplicado el rating del canal. Una segunda temporada del programa israel\u00ed se est\u00e1 grabando.<\/p>\n<p>DMG tambi\u00e9n planea exhibir programas bien establecidos como \u00abDesaf\u00edo Autofoto\u201d, y el nuevo programa \u201c300 segundos de paseo\u201d, un formato de Studio Glam. La comedia rom\u00e1ntica ganadora de m\u00faltiples premios \u201cCiega a Citas\u201d tambi\u00e9n aparecer\u00e1 en LA Screenings a trav\u00e9s de los recientes acuerdos con Fox LATAM para la versi\u00f3n en espa\u00f1ol de la serie y ofertas de formatos en Rusia, Vietnam y China.<\/p>\n<p>Dori Media tambi\u00e9n planea mostrar dos episodios del drama \u201cNew York\u201d, distribuido por NeW Films International, en Lionsgate Latin American Screenings.<\/p>\n<p>Nadav Palti, Presidente y CEO de Dori Media Group, coment\u00f3: \u201c<em>Estamos llevando un cat\u00e1logo diverso y realmente innovador para LA Screenings , que incluye nuevos programas que est\u00e1n camino a convertirse en \u00e9xitos internacionales. Todos nuestros formatos son f\u00e1cilmente adaptables a los gustos locales y estamos particularmente entusiasmados con el potencial de nuestros \u00faltimos formatos de \u00abEsperanza Mia\u00bb y \u00abJuego de Chefs\u00bb que van que capturar la imaginaci\u00f3n de las cadenas internacionales<\/em>\u201d.<\/p>\n<p>Una sinopsis de cada programa que se presentar\u00e1 en LA Screenings por Dori Media puede encontrarse debajo de la gacetilla.<\/p>\n<p><strong><em>\u201cEsperanza M\u00eda\u201d (My Lovely Hope) <\/em><\/strong>es una comedia rom\u00e1ntica sobre un amor prohibido entre Julia (Hope) y Tom\u00e1s. La madre de Julia se muere de una enfermedad que contrajo por la contaminaci\u00f3n que hab\u00eda en la f\u00e1brica donde trabajaba. Justo antes de morir, le pide a Julia que encuentre al due\u00f1o de la f\u00e1brica, pero ella empieza a ser perseguida mientras trata de hacer lo que lo pidi\u00f3 su madre. Se escapa a Buenos Aires y se esconde en un convento, donde pretende ser una monja llamada Esperanza. All\u00ed conoce a un sacerdote que se llama Tom\u00e1s y crece el amor entre ellos. Desafortunadamente, Julia no tiene idea que Tom\u00e1s es el hermano del hombre responsable por la muerte de su madre, el hombre que ella jur\u00f3 llevar ante la justicia. Un tr\u00e1iler del programa puede verse aqu\u00ed: <a href=\"https:\/\/www.youtube.com\/watch?v=m2RZayEBNEQ\">https:\/\/www.youtube.com\/watch?v=m2RZayEBNEQ<\/a><\/p>\n<p>\u201c<strong><em>Juego de Chefs\u201d<\/em><\/strong> es un programa gastron\u00f3mico que se embarca en una b\u00fasqueda a nivel nacional para descubrir un chef superestrella. La competencia est\u00e1 abierta para todos, cocineros amateur y profesionales. El programa consta de tres etapas: Un \u00abCasting\u00bb, un \u00abCampamento militar\u00bb y \u00abBatallas ardientes\u00bb. Las decisiones de las tres etapas est\u00e1n hechas por un panel de tres de los mejores chefs dentro del negocio gastron\u00f3mico \u2013 pero con diferentes puntos de vista. A trav\u00e9s de esta temporada los concursantes compiten individualmente y en equipo, apuntando a convertirse en un super chef!<\/p>\n<p>El eje del show es la relaci\u00f3n compleja entre 3 chefs y sus concursantes, el conflicto entre la amistad y la admiraci\u00f3n profesional, por un lado la competencia y por el otro el deseo de ganarle al otro. Cada chef representa una filosof\u00eda diferente en la vida y en la cocina, cada uno tiene un estilo diferente de cocinar, diferente personalidad, comportamiento y forma de expresarse.<\/p>\n<p>\u00ab<strong>300 segundos de paseo<\/strong>\u00ab, un formato de Estudio Glam, es un programa televisivo en prime time de preguntas y respuestas sobre una plataforma en r\u00e1pido movimiento, donde un equipo de dos concursantes se embarca en un paseo de 5 minutos en el &#8216;Time Track&#8217;, una plataforma \u00fanica en movimiento que va desde un lado del estudio al otro. El equipo debe responder ocho preguntas antes que, literalmente, se acabe el tiempo. Si lo logran, tienen la oportunidad de responder a la Pegunta Final, y ganar un mill\u00f3n de shekels. Una respuesta incorrecta, sin embargo, los devolver\u00e1 a casa con las manos vac\u00edas. El espect\u00e1culo ya ha sido recogido por la ALP, la filial de producci\u00f3n de entretenimiento de Zodiak Medios en Francia , as\u00ed como por Endemol Espa\u00f1a. Un tr\u00e1iler en ingl\u00e9s del programa puede verse aqu\u00ed: https:\/\/www.youtube.com\/watch?v=lQgfwZc5-_g<\/p>\n<p>\u00ab<strong>Desaf\u00edo Autofoto<\/strong>\u201d convirti\u00f3 el \u00faltimo fen\u00f3meno global de tomar selfies en un reality show. Este programa muy contempor\u00e1neo incorpora las mejores cualidades de los formatos de reality y de juego y sigue a dos grupos de amigos, que se encuentran en diferentes lugares del mundo, compitiendo entre s\u00ed por autofotos enviadas en tiempo real. Los desaf\u00edos se vuelven m\u00e1s dif\u00edciles a lo largo de la competici\u00f3n en cinco rounds y los altos niveles de improvisaci\u00f3n y creatividad son necesarios ya que la competencia progresa. \u00abDesaf\u00edo Autofoto\u00bb es un formato de Studio Glam producido en asociaci\u00f3n con NBA Producciones. Dori Media tiene los derechos exclusivos de distribuci\u00f3n global para el formato.<\/p>\n<p>\u201c<strong>Ciega a Citas<\/strong>\u201d es la historia de una mujer que se encuentra inesperadamente en un tri\u00e1ngulo amoroso. Luc\u00eda cree que est\u00e1 enamorada del presentador de un programa de radio, pero no se da cuenta que el verdadero amor de su vida est\u00e1 del otro lado de la pantalla. El amor que no es bueno para ella, la ciega y el amor que la hace feliz no est\u00e1 en su radar. Pero desde que hizo una apuesta con su madre si va a ser capaz de encontrar un hombre antes del casamiento de su hermana, Luc\u00eda hace un gran esfuerzo para conocer tantos hombres como le es posible. Al menos estad\u00edsticamente, uno de ellos tendr\u00e1 que ganarse su coraz\u00f3n. Esta es la remake de la exitosa serie argentina \u201cCiega a Citas\u201d, la cual gan\u00f3 el prestigioso premio Mart\u00edn Fierro y el premio Rose d\u2019Or.<\/p>\n<p>\u201c<strong>Nueva York<\/strong>\u201d es un drama diario con una trama colorida y compleja. El hijo del jefe de una famosa familia del crimen llega a Nueva York, escapando de su pasado y a la b\u00fasqueda de un nuevo futuro. \u00c9l rechaza la sumisi\u00f3n de los trabajadores extranjeros severamente explotados y est\u00e1 decidido a cambiarlo. Al hacerlo, se encontrar\u00e1 con su verdadero destino. \u00abNueva York\u00bb fue producida por Dori Media Darset para el proveedor de televisi\u00f3n DBS de Israel &#8216;SI&#8217;.\u00bbNueva York\u00bb ha sido el drama m\u00e1s visto de todos los tiempos en el canal &#8216;S\u00cd&#8217; y ha aumentado la visualizaci\u00f3n total del canal en un 35 %. \u00abNueva York\u00bb tambi\u00e9n ha ganado el Concurso de Accolade para el \u00abPrograma de Excelencia de Drama \/ Serie 2012\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cEsperanza Mia\u201d es el segundo programa m\u00e1s visto en Argentina y ha tenido el mejor rendimiento en su horario de 9:00 pm desde su debut. \u00a0\u201cJuego de Chefs\u201d est\u00e1 por lanzarse en Alemanis continuando el gran rating en Israel Dori Media Group (\u201cDMG\u201d, \u201cla Compa\u00f1\u00eda\u201d) anuncia que asistir\u00e1 a LA Screenings 2015 con una gran[&#8230;] <\/p>\n<p class=\"mt-15\"><a class=\"btn btn-color btn-sm\" href=\"https:\/\/dorimedia.com\/es\/publications\/la-screenings-2\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-1773","post","type-post","status-publish","format-standard","hentry","category-publications"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS &quot;ESPERANZA MIA&quot; Y &quot;JUEGO DE CHEFS&quot; - DORI MEDIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorimedia.com\/publications\/la-screenings-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS &quot;ESPERANZA MIA&quot; Y &quot;JUEGO DE CHEFS&quot; - DORI MEDIA\" \/>\n<meta property=\"og:description\" content=\"\u201cEsperanza Mia\u201d es el segundo programa m\u00e1s visto en Argentina y ha tenido el mejor rendimiento en su horario de 9:00 pm desde su debut. \u00a0\u201cJuego de Chefs\u201d est\u00e1 por lanzarse en Alemanis continuando el gran rating en Israel Dori Media Group (\u201cDMG\u201d, \u201cla Compa\u00f1\u00eda\u201d) anuncia que asistir\u00e1 a LA Screenings 2015 con una gran[...] Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorimedia.com\/publications\/la-screenings-2\/\" \/>\n<meta property=\"og:site_name\" content=\"DORI MEDIA\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-07T14:17:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-12T13:58:41+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\"},\"headline\":\"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \u00abESPERANZA MIA\u00bb Y \u00abJUEGO DE CHEFS\u00bb\",\"datePublished\":\"2015-05-07T14:17:33+00:00\",\"dateModified\":\"2016-12-12T13:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/\"},\"wordCount\":2486,\"articleSection\":[\"Publications\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/\",\"url\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/\",\"name\":\"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \\\"ESPERANZA MIA\\\" Y \\\"JUEGO DE CHEFS\\\" - DORI MEDIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#website\"},\"datePublished\":\"2015-05-07T14:17:33+00:00\",\"dateModified\":\"2016-12-12T13:58:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/la-screenings-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dorimedia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dori Media Group attends LA Screenings with Significant ratings successes \u201cEsperanza Mia\u201d and \u201cGame of Chefs\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#website\",\"url\":\"https:\\\/\\\/dorimedia.com\\\/\",\"name\":\"DORI MEDIA\",\"description\":\"Dori Media is an international group of media companies with offices is Israel, Switzerland, Argentina and the USA. The groups&#039; business includes production, broadcast (TV channels), distribution and technical services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorimedia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/dorimedia.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \"ESPERANZA MIA\" Y \"JUEGO DE CHEFS\" - DORI MEDIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/","og_locale":"es_ES","og_type":"article","og_title":"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \"ESPERANZA MIA\" Y \"JUEGO DE CHEFS\" - DORI MEDIA","og_description":"\u201cEsperanza Mia\u201d es el segundo programa m\u00e1s visto en Argentina y ha tenido el mejor rendimiento en su horario de 9:00 pm desde su debut. \u00a0\u201cJuego de Chefs\u201d est\u00e1 por lanzarse en Alemanis continuando el gran rating en Israel Dori Media Group (\u201cDMG\u201d, \u201cla Compa\u00f1\u00eda\u201d) anuncia que asistir\u00e1 a LA Screenings 2015 con una gran[...] Read More","og_url":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/","og_site_name":"DORI MEDIA","article_published_time":"2015-05-07T14:17:33+00:00","article_modified_time":"2016-12-12T13:58:41+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/#article","isPartOf":{"@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/"},"author":{"name":"admin","@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389"},"headline":"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \u00abESPERANZA MIA\u00bb Y \u00abJUEGO DE CHEFS\u00bb","datePublished":"2015-05-07T14:17:33+00:00","dateModified":"2016-12-12T13:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/"},"wordCount":2486,"articleSection":["Publications"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/","url":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/","name":"DORI MEDIA GROUP ASISTE A LA SCREENINGS CON LOS \u00c9XITOS \"ESPERANZA MIA\" Y \"JUEGO DE CHEFS\" - DORI MEDIA","isPartOf":{"@id":"https:\/\/dorimedia.com\/#website"},"datePublished":"2015-05-07T14:17:33+00:00","dateModified":"2016-12-12T13:58:41+00:00","author":{"@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389"},"breadcrumb":{"@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorimedia.com\/publications\/la-screenings-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dorimedia.com\/publications\/la-screenings-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dorimedia.com\/"},{"@type":"ListItem","position":2,"name":"Dori Media Group attends LA Screenings with Significant ratings successes \u201cEsperanza Mia\u201d and \u201cGame of Chefs\u201d"}]},{"@type":"WebSite","@id":"https:\/\/dorimedia.com\/#website","url":"https:\/\/dorimedia.com\/","name":"DORI MEDIA","description":"Dori Media is an international group of media companies with offices is Israel, Switzerland, Argentina and the USA. The groups&#039; business includes production, broadcast (TV channels), distribution and technical services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorimedia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/dorimedia.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/1773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/comments?post=1773"}],"version-history":[{"count":4,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/1773\/revisions"}],"predecessor-version":[{"id":2907,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/1773\/revisions\/2907"}],"wp:attachment":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/media?parent=1773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/categories?post=1773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/tags?post=1773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}