{"id":3289,"date":"2019-10-11T06:42:48","date_gmt":"2019-10-11T06:42:48","guid":{"rendered":"https:\/\/dorimedia.com\/?p=3289"},"modified":"2019-10-13T06:43:25","modified_gmt":"2019-10-13T06:43:25","slug":"dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house","status":"publish","type":"post","link":"https:\/\/dorimedia.com\/es\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/","title":{"rendered":"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019"},"content":{"rendered":"<p><\/p>\n<h2><em>El exitoso reality show logra gran \u00e9xito en Argentina con 45% share y <\/em><em>9 puntos de rating desde su estreno por Canal 13<\/em><\/h2>\n<p>Dori Media (\u201cDMG\u201d, \u201c<em>la Empresa<\/em>\u201d) anuncia que ha firmado un acuerdo con Laflia, una productora y distribuidora Argentina de TV, para distribuir el reality show diario \u2018Corte y Confecci\u00f3n\u2019.<\/p>\n<p>Un nuevo reality show de moda busca al mejor talento entre autodidactas, aficionados, estudiantes y profesionales de carreras relacionadas con el dise\u00f1o de moda. Los concursantes compiten para crear la mejor ropa y est\u00e1n condicionados en tiempo, materiales y tema. Sus dise\u00f1os son evaluados por la calidad y la singularidad, pero tambi\u00e9n por la capacidad de adaptarse a tareas estresantes, y uno o m\u00e1s dise\u00f1adores son eliminados cada semana.<\/p>\n<p>La temporada 1 se emiti\u00f3 de enero a junio de 2019 en Canal 13, alcanzando un 45% de share y 9 puntos de rating, y la temporada 2 ya se ha lanzado por la tarde de manera diaria, lo que aumenta sustancialmente los ratings de la tarde del canal. Cada semana, \u00abCorte y Confecci\u00f3n\u00bb presenta a 14 desconocidos dise\u00f1adores fan\u00e1ticos de la moda que compiten para demostrar que su estilo es el mejor, para tener la oportunidad de ganar un premio econ\u00f3mico, una beca en una escuela local de moda y un premio de incentivo.<\/p>\n<p>Nadav Palti, CEO &amp; Presidente de Dori Media Group coment\u00f3:<em> \u201cEstamos encantados de ver el rotundo \u00e9xito de ambas temporadas de \u00abCorte y Confecci\u00f3n\u00bb en Argentina. El reality show se encuentra entre los m\u00e1s vistos en el pa\u00eds y tiene un gran potencial para viajar por la regi\u00f3n y el mundo. La asociaci\u00f3n con Laflia aporta una gran contribuci\u00f3n a nuestros esfuerzos para hacer que el programa sea a\u00fan m\u00e1s popular\u201d.<\/em><\/p>\n<p>Marcelo Tinelli uno de los presentadores m\u00e1s famosos de Argentina y due\u00f1o de Laflia, coment\u00f3: <em>\u201cSiempre soy muy elogioso con el nivel de la televisi\u00f3n argentina, porque s\u00e9 de primera mano acerca de la capacidad y el compromiso de los profesionales que se desempe\u00f1an all\u00ed. Corte y Confecci\u00f3n es un programa que est\u00e1 lleno de sensibilidad y arte; transmite una humanidad que lo acerca mucho al p\u00fablico y tambi\u00e9n le quita ese velo de frivolidad que muchos le endilgan a la moda, para mostrar la vocaci\u00f3n que tantos hombres y mujeres sienten por esta profesi\u00f3n. Creo que el formato de reality, tan recurrente en los \u00faltimos a\u00f1os, tambi\u00e9n trae una f\u00f3rmula balanceada para hacer que el show gane m\u00e1s \u00e9xito\u201d<\/em><\/p>\n<p>Federico Facello, CEO de Laflia coment\u00f3: \u00ab<em>Me genera mucho orgullo que Laflia haya apostado por un producto propio y de calidad como Corte y Confecci\u00f3n; y la recompensa es el reconocimiento del p\u00fablico. <\/em><em>Creo que el formato del programa, tan \u00e1gil y din\u00e1mico, se adapta perfectamente a las nuevas tendencias y exigencias del mercado; y eso es parte fundamental de su atractivo. <\/em><em>La satisfacci\u00f3n con el producto nos compromete m\u00e1s que nunca a seguir apostando por la calidad y los formatos propios; amamos la televisi\u00f3n y el entusiasmo se renueva temporada a temporada\u201d.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>El exitoso reality show logra gran \u00e9xito en Argentina con 45% share y 9 puntos de rating desde su estreno por Canal 13 Dori Media (\u201cDMG\u201d, \u201cla Empresa\u201d) anuncia que ha firmado un acuerdo con Laflia, una productora y distribuidora Argentina de TV, para distribuir el reality show diario \u2018Corte y Confecci\u00f3n\u2019. Un nuevo reality[&#8230;] <\/p>\n<p class=\"mt-15\"><a class=\"btn btn-color btn-sm\" href=\"https:\/\/dorimedia.com\/es\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-3289","post","type-post","status-publish","format-standard","hentry","category-publications"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA\" \/>\n<meta property=\"og:description\" content=\"El exitoso reality show logra gran \u00e9xito en Argentina con 45% share y 9 puntos de rating desde su estreno por Canal 13 Dori Media (\u201cDMG\u201d, \u201cla Empresa\u201d) anuncia que ha firmado un acuerdo con Laflia, una productora y distribuidora Argentina de TV, para distribuir el reality show diario \u2018Corte y Confecci\u00f3n\u2019. Un nuevo reality[...] Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/\" \/>\n<meta property=\"og:site_name\" content=\"DORI MEDIA\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-11T06:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-13T06:43:25+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\"},\"headline\":\"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019\",\"datePublished\":\"2019-10-11T06:42:48+00:00\",\"dateModified\":\"2019-10-13T06:43:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/\"},\"wordCount\":1029,\"articleSection\":[\"Publications\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/\",\"url\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/\",\"name\":\"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#website\"},\"datePublished\":\"2019-10-11T06:42:48+00:00\",\"dateModified\":\"2019-10-13T06:43:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/publications\\\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dorimedia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DORI MEDIA SIGNS COOPERATION AGREEMENT WITH LAFLIA TO DISTRIBUTE \u2018THE FASHION HOUSE\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#website\",\"url\":\"https:\\\/\\\/dorimedia.com\\\/\",\"name\":\"DORI MEDIA\",\"description\":\"Dori Media is an international group of media companies with offices is Israel, Switzerland, Argentina and the USA. The groups&#039; business includes production, broadcast (TV channels), distribution and technical services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorimedia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorimedia.com\\\/#\\\/schema\\\/person\\\/c288a87f9e9ec55e019a3b4633c91389\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/dorimedia.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/","og_locale":"es_ES","og_type":"article","og_title":"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA","og_description":"El exitoso reality show logra gran \u00e9xito en Argentina con 45% share y 9 puntos de rating desde su estreno por Canal 13 Dori Media (\u201cDMG\u201d, \u201cla Empresa\u201d) anuncia que ha firmado un acuerdo con Laflia, una productora y distribuidora Argentina de TV, para distribuir el reality show diario \u2018Corte y Confecci\u00f3n\u2019. Un nuevo reality[...] Read More","og_url":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/","og_site_name":"DORI MEDIA","article_published_time":"2019-10-11T06:42:48+00:00","article_modified_time":"2019-10-13T06:43:25+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/#article","isPartOf":{"@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/"},"author":{"name":"admin","@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389"},"headline":"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019","datePublished":"2019-10-11T06:42:48+00:00","dateModified":"2019-10-13T06:43:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/"},"wordCount":1029,"articleSection":["Publications"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/","url":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/","name":"DORI MEDIA FIRMA ACUERDO DE COOPERACI\u00d3N CON LAFLIA PARA DISTRIBUIR \u2018CORTE Y CONFECCI\u00d3N\u2019 - DORI MEDIA","isPartOf":{"@id":"https:\/\/dorimedia.com\/#website"},"datePublished":"2019-10-11T06:42:48+00:00","dateModified":"2019-10-13T06:43:25+00:00","author":{"@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389"},"breadcrumb":{"@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dorimedia.com\/publications\/dori-media-signs-cooperation-agreement-with-laflia-to-distribute-the-fashion-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dorimedia.com\/"},{"@type":"ListItem","position":2,"name":"DORI MEDIA SIGNS COOPERATION AGREEMENT WITH LAFLIA TO DISTRIBUTE \u2018THE FASHION HOUSE\u2019"}]},{"@type":"WebSite","@id":"https:\/\/dorimedia.com\/#website","url":"https:\/\/dorimedia.com\/","name":"DORI MEDIA","description":"Dori Media is an international group of media companies with offices is Israel, Switzerland, Argentina and the USA. The groups&#039; business includes production, broadcast (TV channels), distribution and technical services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorimedia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dorimedia.com\/#\/schema\/person\/c288a87f9e9ec55e019a3b4633c91389","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cd82945a664d076473a014ca00741525ac8ad7c0f042a97c9ef7e509ac4e15f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/dorimedia.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/3289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/comments?post=3289"}],"version-history":[{"count":2,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/3289\/revisions"}],"predecessor-version":[{"id":3291,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/posts\/3289\/revisions\/3291"}],"wp:attachment":[{"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/media?parent=3289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/categories?post=3289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorimedia.com\/es\/wp-json\/wp\/v2\/tags?post=3289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}